{"id":1658,"date":"2025-08-10T16:26:09","date_gmt":"2025-08-10T19:26:09","guid":{"rendered":"https:\/\/aimurai.com.ar\/calidad\/"},"modified":"2026-01-26T16:05:37","modified_gmt":"2026-01-26T19:05:37","slug":"calidad","status":"publish","type":"page","link":"https:\/\/aimurai.com.ar\/pt-br\/calidad\/","title":{"rendered":"Qualidade"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#182643&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;30vh&#8221; bottom_padding=&#8221;17vh&#8221; top_padding_phone=&#8221;18vh&#8221; bottom_padding_phone=&#8221;7vh&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;696&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; animation_movement_intensity=&#8221;1&#8243; hover_animation=&#8221;zoom&#8221; alignment=&#8221;right&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; position_desktop=&#8221;absolute&#8221; translate_y_desktop=&#8221;-20%&#8221; max_width_custom=&#8221;30%&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h2&#8243; text_color=&#8221;#D9D9D9&#8243; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;QUALIDADE&#8221; font_size=&#8221;9vw&#8221; text_direction=&#8221;default&#8221; font_size_phone=&#8221;15vw&#8221; font_line_height=&#8221;1&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#D9D9D9&#8243; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;O INVIS\u00cdVEL TAMB\u00c9M IMPORTA&#8221; font_size=&#8221;1.3vw&#8221; text_direction=&#8221;default&#8221; font_size_phone=&#8221;3.8vw&#8221; font_line_height=&#8221;1.2&#8243;][\/split_line_heading][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#08529F&#8221; mouse_based_parallax_bg=&#8221;true&#8221; scene_position=&#8221;bottom&#8221; mouse_sensitivity=&#8221;5&#8243; layer_one_image=&#8221;780&#8243; layer_one_strength=&#8221;0.4&#8243; top_padding=&#8221;10%&#8221; bottom_padding=&#8221;0px&#8221; top_padding_phone=&#8221;20%&#8221; bottom_padding_phone=&#8221;0&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;1&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;0px&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;2%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h1&#8243; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;POL\u00cdTICAS DE QUALIDADE E INOCUIDADE&#8221; font_size=&#8221;2.7vw&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243; animation_delay=&#8221;400&#8243; font_size_phone=&#8221;6vw&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_direction=&#8221;default&#8221; animation_delay=&#8221;700&#8243; font_line_height=&#8221;1.4&#8243; font_size=&#8221;20&#8243; text_content=&#8221;Na Aimurai, assumimos um compromisso ativo com a qualidade, a inocuidade e a autenticidade de tudo o que produzimos.&#8221; font_size_phone=&#8221;16&#8243;]\n[\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_direction=&#8221;default&#8221; animation_delay=&#8221;700&#8243; font_line_height=&#8221;1.5&#8243; text_content=&#8221;Nosso sistema de gest\u00e3o \u00e9 baseado em processos certificados, tecnologia de alto desempenho e uma equipe capacitada para garantir a rastreabilidade desde a mat\u00e9ria-prima at\u00e9 o produto final.&#8221; font_size=&#8221;20&#8243; font_size_phone=&#8221;16&#8243;]20[\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;bottom&#8221; column_margin=&#8221;90px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;column_reverse&#8221; top_padding=&#8221;4%&#8221; bottom_padding=&#8221;0px&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; bottom_margin=&#8221;0&#8243; bottom_margin_phone=&#8221;0&#8243; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][image_with_animation image_url=&#8221;706&#8243; image_size=&#8221;full&#8221; max_width=&#8221;150%&#8221; max_width_mobile=&#8221;110%&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In From Left&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; bottom_position_desktop=&#8221;0&#8243; bottom_position_phone=&#8221;0&#8243; translate_y_desktop=&#8221;50px&#8221; translate_x_desktop=&#8221;-16%&#8221; translate_y_phone=&#8221;0&#8243; translate_x_phone=&#8221;-25%&#8221; margin_top=&#8221;0&#8243; margin_bottom=&#8221;0&#8243; delay=&#8221;200&#8243; margin_bottom_phone=&#8221;0&#8243;][\/vc_column_inner][vc_column_inner bottom_padding_desktop=&#8221;0&#8243; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;zoom-out-slow&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;advanced&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h1&#8243; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_direction=&#8221;default&#8221; animation_delay=&#8221;700&#8243; font_line_height=&#8221;1.6&#8243; font_size=&#8221;22&#8243; text_content=&#8221;Trabalhamos com crit\u00e9rios claros&#8221; font_size_phone=&#8221;20&#8243;][\/split_line_heading]<div class=\"nectar-fancy-ul font_size_desktop_1vw font_size_phone_16px\" data-list-icon=\"icon-salient-check\" data-animation=\"true\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"15px\" data-alignment=\"left\"> \n<ul>\n<li>Cumprir os requisitos dos clientes, regulat\u00f3rios e legais.<\/li>\n<li>Produzir alimentos seguros, legais e confi\u00e1veis.<\/li>\n<li>Ouvir e responder com agilidade \u00e0s necessidades do mercado.<\/li>\n<li>Capacitar continuamente nossa equipe em temas-chave para assegurar o cumprimento dos mais altos padr\u00f5es.<\/li>\n<li>Otimizar o processo produtivo com foco em efici\u00eancia, tecnologia e melhoria cont\u00ednua.<\/li>\n<li>Promover rela\u00e7\u00f5es respons\u00e1veis com fornecedores que compartilhem nossos crit\u00e9rios de qualidade e inocuidade.<\/li>\n<li>Consolidar um sistema de gest\u00e3o que integre seguran\u00e7a, transpar\u00eancia e preven\u00e7\u00e3o de fraudes alimentares.<\/li>\n<li>Operar sob uma vis\u00e3o sustent\u00e1vel, cumprindo normas ambientais e trabalhistas, e revisando permanentemente nossos objetivos.<\/li>\n<\/ul>\n <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;281&#8243; bg_image_type=&#8221;default&#8221; bg_position=&#8221;left top&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;8%&#8221; bottom_padding=&#8221;6%&#8221; left_padding_desktop=&#8221;4vw&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;4vw&#8221; top_padding_phone=&#8221;20%&#8221; bottom_padding_phone=&#8221;10%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;custom&#8221; row_border_radius_applies=&#8221;bg&#8221; top_right_border_radius=&#8221;170&#8243; zindex=&#8221;1000000000000000&#8243; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; color_overlay=&#8221;#FFFFFF&#8221; overlay_strength=&#8221;0.8&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;363&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; animation_movement_intensity=&#8221;1&#8243; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;10%&#8221; max_width_custom_phone=&#8221;30%&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;2%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;0px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;letter-reveal-bottom&#8221; font_style=&#8221;h1&#8243; stagger_animation=&#8221;true&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;CERTIFICA\u00c7\u00d5ES&#8221; font_size=&#8221;2.7vw&#8221; text_direction=&#8221;default&#8221; font_line_height=&#8221;1&#8243; animation_delay=&#8221;400&#8243; font_size_phone=&#8221;8vw&#8221;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; top_margin_phone=&#8221;-6%&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221; content_layout=&#8221;default&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_direction=&#8221;default&#8221; animation_delay=&#8221;700&#8243; font_line_height=&#8221;1.4&#8243; font_size=&#8221;20&#8243; text_content=&#8221;Nosso compromisso com a qualidade n\u00e3o \u00e9 apenas um conceito, \u00e9 uma pr\u00e1tica sustentada por sistemas de gest\u00e3o, controles e auditorias permanentes.&#8221; font_size_phone=&#8221;16&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_direction=&#8221;default&#8221; animation_delay=&#8221;700&#8243; font_line_height=&#8221;1.5&#8243; text_content=&#8221;Como resultado desse trabalho cont\u00ednuo, contamos com certifica\u00e7\u00f5es que validam nossos processos em termos de seguran\u00e7a alimentar, conformidade regulat\u00f3ria e padr\u00f5es internacionais.&#8221; font_size=&#8221;20&#8243; font_size_phone=&#8221;16&#8243;]20[\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-6-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#08529F&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_left_border_radius=&#8221;70&#8243; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;730&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;44%&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;FOOD SAFETY SYSTEM CERTIFICATION 22000&#8243; font_size=&#8221;22&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;20&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Certifica\u00e7\u00e3o reconhecida globalmente que garante um sistema de gest\u00e3o da inocuidade alimentar robusto e eficaz.&#8221; font_size=&#8221;20&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Baseada nos padr\u00f5es ISO e nos princ\u00edpios de melhoria cont\u00ednua, a FSSC 22000 assegura que nossos processos atendem aos requisitos mais rigorosos em seguran\u00e7a alimentar, rastreabilidade e controle de riscos. Essa certifica\u00e7\u00e3o \u00e9 reconhecida pela Global Food Safety Initiative (GFSI) e refor\u00e7a nossa capacidade de atuar nos mercados internacionais com transpar\u00eancia e confian\u00e7a.&#8221; font_size=&#8221;18&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-6-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#08529F&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; top_right_border_radius=&#8221;70&#8243; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;732&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;18%&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;BRCGS FOOD \u2013 VERS\u00c3O 8&#8243; font_size=&#8221;22&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;20&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Certifica\u00e7\u00e3o internacional que atesta a seguran\u00e7a e a qualidade de produtos agroalimentares.&#8221; font_size=&#8221;20&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;A vers\u00e3o 8 fortalece o papel ativo da gest\u00e3o e a implementa\u00e7\u00e3o de sistemas de controle preventivos, voltados a garantir produtos seguros, legais e consistentes.&#8221; font_size=&#8221;18&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;]\n<p>18<\/p>\n[\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-6-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#08529F&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;733&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;12%&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;KOSHER&#8221; font_size=&#8221;22&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;20&#8243;]4[\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Certifica\u00e7\u00e3o que assegura o cumprimento das normas alimentares da comunidade judaica.&#8221; font_size=&#8221;20&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Validamos processos e mat\u00e9rias-primas que respeitam as exig\u00eancias dessa tradi\u00e7\u00e3o, garantindo um produto adequado ao consumo de acordo com os princ\u00edpios da dieta hebraica.&#8221; font_size=&#8221;18&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;][\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-6-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#08529F&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; bottom_right_border_radius=&#8221;70&#8243; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;734&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;20%&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;CERTIFICADO DE REGISTRO DE ESTABELECIMENTO NA FDA&#8221; font_size=&#8221;22&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;20&#8243;]4[\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Possu\u00edmos registro junto \u00e0 FDA (Food and Drug Administration), requisito indispens\u00e1vel para exportar produtos aos Estados Unidos.&#8221; font_size=&#8221;20&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Esse reconhecimento garante que nossas instala\u00e7\u00f5es atendem aos padr\u00f5es exigidos para a elabora\u00e7\u00e3o, o processamento e o armazenamento de alimentos destinados ao consumo humano e animal.&#8221; font_size=&#8221;18&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;]\n[\/split_line_heading][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-6-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;padding-6-percent&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;10px&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#08529F&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;custom&#8221; bottom_right_border_radius=&#8221;70&#8243; bottom_left_border_radius=&#8221;70&#8243; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; content_layout=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;735&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;16%&#8221;][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;SELO ALIMENTOS ARGENTINOS&#8221; font_size=&#8221;22&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;20&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Este selo distingue alimentos produzidos no pa\u00eds que atendem a elevados padr\u00f5es de qualidade na categoria Premium.&#8221; font_size=&#8221;20&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;][\/split_line_heading][split_line_heading line_reveal_by_space_text_effect=&#8221;default&#8221; font_style=&#8221;p&#8221; text_color=&#8221;#FFFFFF&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; animation_type=&#8221;line-reveal-by-space&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Respaldamos as\u00ed una identidad nacional s\u00f3lida y una propuesta confiable, reconocida tanto en el mercado local como en el internacional.&#8221; font_size=&#8221;18&#8243; text_direction=&#8221;default&#8221; font_size_phone=&#8221;16&#8243;]\n[\/split_line_heading][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#182643&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;30vh&#8221; bottom_padding=&#8221;17vh&#8221; top_padding_phone=&#8221;18vh&#8221; bottom_padding_phone=&#8221;7vh&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1658","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qualidade - AIMURAI::. El gusto por lo bueno<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aimurai.com.ar\/pt-br\/calidad\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qualidade - AIMURAI::. El gusto por lo bueno\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#182643&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;30vh&#8221; bottom_padding=&#8221;17vh&#8221; top_padding_phone=&#8221;18vh&#8221; bottom_padding_phone=&#8221;7vh&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aimurai.com.ar\/pt-br\/calidad\/\" \/>\n<meta property=\"og:site_name\" content=\"AIMURAI::. El gusto por lo bueno\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61560702962739\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T19:05:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/pt-br\\\/calidad\\\/\",\"url\":\"https:\\\/\\\/aimurai.com.ar\\\/pt-br\\\/calidad\\\/\",\"name\":\"Qualidade - AIMURAI::. El gusto por lo bueno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/#website\"},\"datePublished\":\"2025-08-10T19:26:09+00:00\",\"dateModified\":\"2026-01-26T19:05:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/pt-br\\\/calidad\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aimurai.com.ar\\\/pt-br\\\/calidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/pt-br\\\/calidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aimurai.com.ar\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qualidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/#website\",\"url\":\"https:\\\/\\\/aimurai.com.ar\\\/\",\"name\":\"AIMURAI::. El gusto por lo bueno\",\"description\":\"Producimos aceite de oliva y derivados como se cultiva un legado. Nuestro compromiso se mantiene inalterable: calidad sin concesiones.\",\"publisher\":{\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aimurai.com.ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/#organization\",\"name\":\"AIMURAI::. El gusto por lo bueno\",\"url\":\"https:\\\/\\\/aimurai.com.ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aimurai.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-viJHTO.svg\",\"contentUrl\":\"https:\\\/\\\/aimurai.com.ar\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-viJHTO.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"AIMURAI::. El gusto por lo bueno\"},\"image\":{\"@id\":\"https:\\\/\\\/aimurai.com.ar\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61560702962739\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCO5b6t_h8z5YfXp1f0eQ0zA\",\"https:\\\/\\\/www.instagram.com\\\/aimuraioficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qualidade - AIMURAI::. El gusto por lo bueno","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aimurai.com.ar\/pt-br\/calidad\/","og_locale":"pt_BR","og_type":"article","og_title":"Qualidade - AIMURAI::. El gusto por lo bueno","og_description":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#182643&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;30vh&#8221; bottom_padding=&#8221;17vh&#8221; top_padding_phone=&#8221;18vh&#8221; bottom_padding_phone=&#8221;7vh&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221;...","og_url":"https:\/\/aimurai.com.ar\/pt-br\/calidad\/","og_site_name":"AIMURAI::. El gusto por lo bueno","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61560702962739","article_modified_time":"2026-01-26T19:05:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aimurai.com.ar\/pt-br\/calidad\/","url":"https:\/\/aimurai.com.ar\/pt-br\/calidad\/","name":"Qualidade - AIMURAI::. El gusto por lo bueno","isPartOf":{"@id":"https:\/\/aimurai.com.ar\/#website"},"datePublished":"2025-08-10T19:26:09+00:00","dateModified":"2026-01-26T19:05:37+00:00","breadcrumb":{"@id":"https:\/\/aimurai.com.ar\/pt-br\/calidad\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aimurai.com.ar\/pt-br\/calidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aimurai.com.ar\/pt-br\/calidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aimurai.com.ar\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Qualidade"}]},{"@type":"WebSite","@id":"https:\/\/aimurai.com.ar\/#website","url":"https:\/\/aimurai.com.ar\/","name":"AIMURAI::. El gusto por lo bueno","description":"Producimos aceite de oliva y derivados como se cultiva un legado. Nuestro compromiso se mantiene inalterable: calidad sin concesiones.","publisher":{"@id":"https:\/\/aimurai.com.ar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aimurai.com.ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/aimurai.com.ar\/#organization","name":"AIMURAI::. El gusto por lo bueno","url":"https:\/\/aimurai.com.ar\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aimurai.com.ar\/#\/schema\/logo\/image\/","url":"https:\/\/aimurai.com.ar\/wp-content\/uploads\/2025\/07\/logo-viJHTO.svg","contentUrl":"https:\/\/aimurai.com.ar\/wp-content\/uploads\/2025\/07\/logo-viJHTO.svg","width":"1024","height":"1024","caption":"AIMURAI::. El gusto por lo bueno"},"image":{"@id":"https:\/\/aimurai.com.ar\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61560702962739","https:\/\/www.youtube.com\/channel\/UCO5b6t_h8z5YfXp1f0eQ0zA","https:\/\/www.instagram.com\/aimuraioficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/aimurai.com.ar\/pt-br\/wp-json\/wp\/v2\/pages\/1658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aimurai.com.ar\/pt-br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aimurai.com.ar\/pt-br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aimurai.com.ar\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aimurai.com.ar\/pt-br\/wp-json\/wp\/v2\/comments?post=1658"}],"version-history":[{"count":1,"href":"https:\/\/aimurai.com.ar\/pt-br\/wp-json\/wp\/v2\/pages\/1658\/revisions"}],"predecessor-version":[{"id":1659,"href":"https:\/\/aimurai.com.ar\/pt-br\/wp-json\/wp\/v2\/pages\/1658\/revisions\/1659"}],"wp:attachment":[{"href":"https:\/\/aimurai.com.ar\/pt-br\/wp-json\/wp\/v2\/media?parent=1658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}